{"id":10485,"date":"2018-09-27T10:39:26","date_gmt":"2018-09-27T08:39:26","guid":{"rendered":"https:\/\/cimarelliporte.it\/2021\/project\/art-3160\/"},"modified":"2021-07-13T15:27:20","modified_gmt":"2021-07-13T13:27:20","slug":"art-3160","status":"publish","type":"project","link":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/","title":{"rendered":"Art. 3160"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243;][et_pb_row column_structure=&#8221;1_5,3_5,1_5&#8243; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-art-3160-suzuca-cimarelli-porte-alluminio-bugnall.jpg&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine Principale&#8221; _builder_version=&#8221;3.23&#8243;][\/et_pb_image][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;3.15&#8243; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#888b89&#8243; title_font_size=&#8221;36px&#8221; text_orientation=&#8221;center&#8221;][\/et_pb_post_title][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243;][et_pb_row column_structure=&#8221;1_2,1_4,1_4&#8243; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Testo &#8211; descrizione articolo&#8221; _builder_version=&#8221;4.9.7&#8243; border_width_right=&#8221;1px&#8221; border_color_right=&#8221;#888b89&#8243;]<\/p>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h2>Art. 3160<\/h2>\n<h2>linea design<\/h2>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Testo &#8211; misure pannello&#8221; _builder_version=&#8221;3.27.4&#8243;]<\/p>\n<p>\n<strong>Misure standard pannello *<br \/><\/strong><\/p>\n<p>90 x 215 cm<\/p>\n<hr \/>\n<p><strong>Misure disponibili **\u00a0 <\/strong><\/p>\n<p>L: da 44 a 90 cm | H: da 176 a 215 cm<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Testo &#8211; maggiori info&#8221; _builder_version=&#8221;3.27.4&#8243; background_color=&#8221;#f7f7f7&#8243; saved_tabs=&#8221;all&#8221;]<\/p>\n<p>Per gli <a title=\"Caratteristiche Tecniche dei Pannelli\" href=\"https:\/\/cimarelliporte.it\/2021\/2021-italia\/caratteristiche-pannelli\/\">spessori e dettagli dei pannelli<\/a> ed i <a title=\"Colori disponibili\" href=\"https:\/\/cimarelliporte.it\/2021\/2021-italia\/colori-disponibili\/\">colori disponibili<\/a>, cliccare qui o\u00a0 sulle icone a destra<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-art-non-esiste-3160.gif&#8221; show_in_lightbox=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine tecnica&#8221; _builder_version=&#8221;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; _builder_version=&#8221;3.22&#8243; background_color=&#8221;#dddddd&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Testo %22asterischi%22&#8243; _builder_version=&#8221;3.27.4&#8243;]<\/p>\n<h6>* foto illustrata<br \/>** le misure disponibili mantengono la bugnatura della stessa dimensione nei rispettivi assi verticale ed orizzontale aggiungiendo o diminuendo materiale al pannello.<\/h6>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; admin_label=&#8221;Riga&#8221; _builder_version=&#8221;3.25&#8243;][et_pb_column_inner type=&#8221;1_4&#8243; saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-scheda-tecnica.png&#8221; url=&#8221;http:\/\/cimarelliporte.it\/porte-alluminio\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-art-3160.pdf&#8221; url_new_window=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine &#8211; scheda tecnica&#8221; _builder_version=&#8221;3.23&#8243;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_4&#8243; saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-specifiche-pannelli.png&#8221; url=&#8221;http:\/\/cimarelliporte.it\/porte-alluminio\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-spessori-composizione-porte-colori_bugnall_cimarelli_2018.pdf&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine &#8211; pannelli spessori&#8221; _builder_version=&#8221;3.23&#8243;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_4&#8243; saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-colorazioni.png&#8221; url=&#8221;http:\/\/cimarelliporte.it\/porte-alluminio\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-colori_bugnall_cimarelli_2018.pdf&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine &#8211; colori&#8221; _builder_version=&#8221;3.23&#8243;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_4&#8243; saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-accessori.png&#8221; url=&#8221;http:\/\/cimarelliporte.it\/porte-alluminio\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-accessori_bugnall_cimarelli_2018.pdf&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine &#8211; accessori&#8221; _builder_version=&#8221;3.23&#8243;][\/et_pb_image][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art. 3160 linea design Misure standard pannello * 90 x 215 cm Misure disponibili **\u00a0 L: da 44 a 90 cm | H: da 176 a 215 cm Per gli spessori e dettagli dei pannelli ed i colori disponibili, cliccare qui o\u00a0 sulle icone a destra* foto illustrata** le misure disponibili mantengono la bugnatura della [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":11539,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[89],"project_tag":[],"class_list":["post-10485","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-modern-line"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Art. 3160 - Cimarelli Porte in Alluminio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Art. 3160 - Cimarelli Porte in Alluminio\" \/>\n<meta property=\"og:description\" content=\"Art. 3160 linea design Misure standard pannello * 90 x 215 cm Misure disponibili **\u00a0 L: da 44 a 90 cm | H: da 176 a 215 cm Per gli spessori e dettagli dei pannelli ed i colori disponibili, cliccare qui o\u00a0 sulle icone a destra* foto illustrata** le misure disponibili mantengono la bugnatura della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/\" \/>\n<meta property=\"og:site_name\" content=\"Cimarelli Porte in Alluminio\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-13T13:27:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-art-3160-suzuca-cimarelli-porte-alluminio-bugnall.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-3160\\\/\",\"url\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-3160\\\/\",\"name\":\"Art. 3160 - Cimarelli Porte in Alluminio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-3160\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-3160\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cimarelliporte.it\\\/2021\\\/wp-content\\\/uploads\\\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3160.jpg\",\"datePublished\":\"2018-09-27T08:39:26+00:00\",\"dateModified\":\"2021-07-13T13:27:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-3160\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-3160\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-3160\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cimarelliporte.it\\\/2021\\\/wp-content\\\/uploads\\\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3160.jpg\",\"contentUrl\":\"https:\\\/\\\/cimarelliporte.it\\\/2021\\\/wp-content\\\/uploads\\\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3160.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"\\\/var\\\/www\\\/vhosts\\\/cimarelliporte.it\\\/httpdocs\\\/2021\\\/wp content\\\/uploads\\\/cimarelli porte pannelli alluminio bugnall cimarelli 3160\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-3160\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\\\/\\\/cimarelliporte.it\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Art. 3160\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/#website\",\"url\":\"https:\\\/\\\/cimarelliporte.it\\\/\",\"name\":\"Cimarelli Porte in Alluminio\",\"description\":\"dal 1970 porte e pannelli in alluminio, classiche, moderne e blindate\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cimarelliporte.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Art. 3160 - Cimarelli Porte in Alluminio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/","og_locale":"en_US","og_type":"article","og_title":"Art. 3160 - Cimarelli Porte in Alluminio","og_description":"Art. 3160 linea design Misure standard pannello * 90 x 215 cm Misure disponibili **\u00a0 L: da 44 a 90 cm | H: da 176 a 215 cm Per gli spessori e dettagli dei pannelli ed i colori disponibili, cliccare qui o\u00a0 sulle icone a destra* foto illustrata** le misure disponibili mantengono la bugnatura della [&hellip;]","og_url":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/","og_site_name":"Cimarelli Porte in Alluminio","article_modified_time":"2021-07-13T13:27:20+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-art-3160-suzuca-cimarelli-porte-alluminio-bugnall.jpg","type":"image\/jpeg"}],"twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/","url":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/","name":"Art. 3160 - Cimarelli Porte in Alluminio","isPartOf":{"@id":"https:\/\/cimarelliporte.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/#primaryimage"},"image":{"@id":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/#primaryimage"},"thumbnailUrl":"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3160.jpg","datePublished":"2018-09-27T08:39:26+00:00","dateModified":"2021-07-13T13:27:20+00:00","breadcrumb":{"@id":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cimarelliporte.it\/en\/project\/art-3160\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/#primaryimage","url":"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3160.jpg","contentUrl":"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3160.jpg","width":2000,"height":2000,"caption":"\/var\/www\/vhosts\/cimarelliporte.it\/httpdocs\/2021\/wp content\/uploads\/cimarelli porte pannelli alluminio bugnall cimarelli 3160"},{"@type":"BreadcrumbList","@id":"https:\/\/cimarelliporte.it\/en\/project\/art-3160\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cimarelliporte.it\/en\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/cimarelliporte.it\/project\/"},{"@type":"ListItem","position":3,"name":"Art. 3160"}]},{"@type":"WebSite","@id":"https:\/\/cimarelliporte.it\/#website","url":"https:\/\/cimarelliporte.it\/","name":"Cimarelli Porte in Alluminio","description":"dal 1970 porte e pannelli in alluminio, classiche, moderne e blindate","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cimarelliporte.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project\/10485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/comments?post=10485"}],"version-history":[{"count":0,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project\/10485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/media\/11539"}],"wp:attachment":[{"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/media?parent=10485"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project_category?post=10485"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project_tag?post=10485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}