{"id":10256,"date":"2023-06-15T16:00:00","date_gmt":"2023-06-15T14:00:00","guid":{"rendered":"https:\/\/cimarelliporte.it\/2021\/project\/art-2050\/"},"modified":"2023-06-28T17:07:22","modified_gmt":"2023-06-28T15:07:22","slug":"art-2050","status":"publish","type":"project","link":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/","title":{"rendered":"Art. 3640"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_5,3_5,1_5&#8243; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640.jpg&#8221; title_text=&#8221;cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640&#8243; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine Principale&#8221; _builder_version=&#8221;4.21.0&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#888b89&#8243; title_font_size=&#8221;36px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_title][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_4,1_4&#8243; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Testo &#8211; descrizione articolo&#8221; _builder_version=&#8221;4.16&#8243; border_width_right=&#8221;1px&#8221; border_color_right=&#8221;#888b89&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h2>Art. 3640<\/h2>\n<h2>Linea classica<\/h2>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Testo &#8211; misure pannello&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>\n<strong>Misure standard pannello *<br \/>\n<\/strong><\/p>\n<p>90 x 215 cm<\/p>\n<hr \/>\n<p><strong>Misure disponibili **\u00a0 <\/strong><\/p>\n<p>L: da 63 a 90 cm | H: da 178 a 215 cm<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Testo &#8211; maggiori info&#8221; _builder_version=&#8221;3.14&#8243; background_color=&#8221;#f7f7f7&#8243; global_module=&#8221;5147&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Per gli <a title=\"Caratteristiche Tecniche dei Pannelli\" href=\"https:\/\/cimarelliporte.it\/2021\/2021-italia\/caratteristiche-pannelli\/\">spessori e dettagli dei pannelli<\/a> ed i <a title=\"Colori disponibili\" href=\"https:\/\/cimarelliporte.it\/2021\/2021-italia\/colori-disponibili\/\">colori disponibili<\/a>, cliccare qui o\u00a0 sulle icone a destra<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/porte-alluminio\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-art-550-2050.gif&#8221; show_in_lightbox=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine tecnica&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#dddddd&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-icona-pdf-download-scheda-prodotto.png&#8221; alt=&#8221;PDF PRODOTTO&#8221; title_text=&#8221;PDF PRODOTTO&#8221; url=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-3640.pdf&#8221; url_new_window=&#8221;on&#8221; use_overlay=&#8221;on&#8221; overlay_icon_color=&#8221;#E09900&#8243; hover_overlay_color=&#8221;rgba(255,255,255,0.89)&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine &#8211; scheda tecnica&#8221; _builder_version=&#8221;4.21.0&#8243; custom_margin=&#8221;||18px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; border_width_top=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>PDF SCHEDA PRODOTTO<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Testo %22asterischi%22&#8243; _builder_version=&#8221;4.16&#8243; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6>* foto illustrata<br \/>** le misure disponibili mantengono la bugnatura della stessa dimensione nei rispettivi assi verticale ed orizzontale aggiungiendo o diminuendo materiale al pannello.<\/h6>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; admin_label=&#8221;Riga&#8221; _builder_version=&#8221;4.16&#8243; global_module=&#8221;12883&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-icona-accessori-catalogo-bugnall-2023.jpg&#8221; alt=&#8221;Accessori PDF&#8221; title_text=&#8221;Accessori PDF&#8221; url=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-accessori-catalogo-bugnall-2023.pdf&#8221; url_new_window=&#8221;on&#8221; use_overlay=&#8221;on&#8221; overlay_icon_color=&#8221;#E09900&#8243; hover_overlay_color=&#8221;rgba(255,255,255,0.89)&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine &#8211; accessori&#8221; _builder_version=&#8221;4.21.0&#8243; custom_margin=&#8221;||18px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; border_width_top=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>PDF ACCESSORI<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-icona-spessori-e-composizioni-catalogo-bugnall-2023.jpg&#8221; alt=&#8221;Spessori e Composizioni PDF&#8221; title_text=&#8221;Spessori e Composizioni PDF&#8221; url=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-spessori-e-composizioni-catalogo-bugnall-2023.pdf&#8221; url_new_window=&#8221;on&#8221; use_overlay=&#8221;on&#8221; overlay_icon_color=&#8221;#E09900&#8243; hover_overlay_color=&#8221;rgba(255,255,255,0.89)&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine &#8211; pannelli spessori&#8221; _builder_version=&#8221;4.21.0&#8243; custom_margin=&#8221;||18px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; border_width_top=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>PDF ASPESSORI E COMPOSIZIONI<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-icona-colori-catalogo-bugnall-2023.jpg&#8221; alt=&#8221;Colori PDF&#8221; title_text=&#8221;Colori PDF&#8221; url=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-colori-catalogo-bugnall-2023.pdf&#8221; url_new_window=&#8221;on&#8221; use_overlay=&#8221;on&#8221; overlay_icon_color=&#8221;#E09900&#8243; hover_overlay_color=&#8221;rgba(255,255,255,0.89)&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine &#8211; colori&#8221; _builder_version=&#8221;4.21.0&#8243; custom_margin=&#8221;||18px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; border_width_top=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>PDF COLORI<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-icona-area-tecnica-catalogo-bugnall-2023.jpg&#8221; alt=&#8221;Area Tecnica PDF&#8221; title_text=&#8221;Area Tecnica PDF&#8221; url=&#8221;https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-area-tecnica-catalogo-bugnall-2023.pdf&#8221; url_new_window=&#8221;on&#8221; use_overlay=&#8221;on&#8221; overlay_icon_color=&#8221;#E09900&#8243; hover_overlay_color=&#8221;rgba(255,255,255,0.89)&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Immagine &#8211; scheda tecnica&#8221; _builder_version=&#8221;4.21.0&#8243; custom_margin=&#8221;||18px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; border_width_top=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>PDF AREA TECNICA<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art. 3640 Linea classica Misure standard pannello * 90 x 215 cm Misure disponibili **\u00a0 L: da 63 a 90 cm | H: da 178 a 215 cm Per gli spessori e dettagli dei pannelli ed i colori disponibili, cliccare qui o\u00a0 sulle icone a destra PDF SCHEDA PRODOTTO* foto illustrata** le misure disponibili mantengono [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":11593,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[87],"project_tag":[],"class_list":["post-10256","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-classic-line"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Art. 3640 - Cimarelli Porte in Alluminio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Art. 3640 - Cimarelli Porte in Alluminio\" \/>\n<meta property=\"og:description\" content=\"Art. 3640 Linea classica Misure standard pannello * 90 x 215 cm Misure disponibili **\u00a0 L: da 63 a 90 cm | H: da 178 a 215 cm Per gli spessori e dettagli dei pannelli ed i colori disponibili, cliccare qui o\u00a0 sulle icone a destra PDF SCHEDA PRODOTTO* foto illustrata** le misure disponibili mantengono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/\" \/>\n<meta property=\"og:site_name\" content=\"Cimarelli Porte in Alluminio\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T15:07:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-2050\\\/\",\"url\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-2050\\\/\",\"name\":\"Art. 3640 - Cimarelli Porte in Alluminio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-2050\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-2050\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cimarelliporte.it\\\/2021\\\/wp-content\\\/uploads\\\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640.jpg\",\"datePublished\":\"2023-06-15T14:00:00+00:00\",\"dateModified\":\"2023-06-28T15:07:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-2050\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-2050\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-2050\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cimarelliporte.it\\\/2021\\\/wp-content\\\/uploads\\\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640.jpg\",\"contentUrl\":\"https:\\\/\\\/cimarelliporte.it\\\/2021\\\/wp-content\\\/uploads\\\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"\\\/var\\\/www\\\/vhosts\\\/cimarelliporte.it\\\/httpdocs\\\/2021\\\/wp content\\\/uploads\\\/cimarelli porte pannelli alluminio bugnall cimarelli 3640\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/project\\\/art-2050\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cimarelliporte.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\\\/\\\/cimarelliporte.it\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Art. 3640\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cimarelliporte.it\\\/#website\",\"url\":\"https:\\\/\\\/cimarelliporte.it\\\/\",\"name\":\"Cimarelli Porte in Alluminio\",\"description\":\"dal 1970 porte e pannelli in alluminio, classiche, moderne e blindate\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cimarelliporte.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Art. 3640 - Cimarelli Porte in Alluminio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/","og_locale":"en_US","og_type":"article","og_title":"Art. 3640 - Cimarelli Porte in Alluminio","og_description":"Art. 3640 Linea classica Misure standard pannello * 90 x 215 cm Misure disponibili **\u00a0 L: da 63 a 90 cm | H: da 178 a 215 cm Per gli spessori e dettagli dei pannelli ed i colori disponibili, cliccare qui o\u00a0 sulle icone a destra PDF SCHEDA PRODOTTO* foto illustrata** le misure disponibili mantengono [&hellip;]","og_url":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/","og_site_name":"Cimarelli Porte in Alluminio","article_modified_time":"2023-06-28T15:07:22+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640.jpg","type":"image\/jpeg"}],"twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/","url":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/","name":"Art. 3640 - Cimarelli Porte in Alluminio","isPartOf":{"@id":"https:\/\/cimarelliporte.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/#primaryimage"},"image":{"@id":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/#primaryimage"},"thumbnailUrl":"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640.jpg","datePublished":"2023-06-15T14:00:00+00:00","dateModified":"2023-06-28T15:07:22+00:00","breadcrumb":{"@id":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cimarelliporte.it\/en\/project\/art-2050\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/#primaryimage","url":"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640.jpg","contentUrl":"https:\/\/cimarelliporte.it\/2021\/wp-content\/uploads\/cimarelli-porte-pannelli-alluminio-bugnall-cimarelli-3640.jpg","width":2000,"height":2000,"caption":"\/var\/www\/vhosts\/cimarelliporte.it\/httpdocs\/2021\/wp content\/uploads\/cimarelli porte pannelli alluminio bugnall cimarelli 3640"},{"@type":"BreadcrumbList","@id":"https:\/\/cimarelliporte.it\/en\/project\/art-2050\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cimarelliporte.it\/en\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/cimarelliporte.it\/project\/"},{"@type":"ListItem","position":3,"name":"Art. 3640"}]},{"@type":"WebSite","@id":"https:\/\/cimarelliporte.it\/#website","url":"https:\/\/cimarelliporte.it\/","name":"Cimarelli Porte in Alluminio","description":"dal 1970 porte e pannelli in alluminio, classiche, moderne e blindate","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cimarelliporte.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project\/10256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/comments?post=10256"}],"version-history":[{"count":0,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project\/10256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/media\/11593"}],"wp:attachment":[{"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/media?parent=10256"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project_category?post=10256"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/cimarelliporte.it\/en\/wp-json\/wp\/v2\/project_tag?post=10256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}